{"id":528,"date":"2026-03-20T09:19:14","date_gmt":"2026-03-20T01:19:14","guid":{"rendered":"https:\/\/www.tirerecyclingline.com\/?p=528"},"modified":"2026-03-20T09:19:14","modified_gmt":"2026-03-20T01:19:14","slug":"faq","status":"publish","type":"post","link":"https:\/\/www.tirerecyclingline.com\/pt\/faq\/","title":{"rendered":"Perguntas Frequentes"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_eef2f7-0b{margin-top:0px;}.kb-row-layout-id528_eef2f7-0b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_eef2f7-0b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_eef2f7-0b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);min-height:200px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id528_eef2f7-0b{background-color:#447ebd;}.kb-row-layout-id528_eef2f7-0b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_eef2f7-0b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id528_eef2f7-0b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_eef2f7-0b alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_c8402e-1a > .kt-inside-inner-col,.kadence-column528_c8402e-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_c8402e-1a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_c8402e-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_c8402e-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_c8402e-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_c8402e-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column528_c8402e-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_c8402e-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_c8402e-1a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa, .wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa[data-kb-block=\"kb-adv-heading528_084457-aa\"]{font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa[data-kb-block=\"kb-adv-heading528_084457-aa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_084457-aa[data-kb-block=\"kb-adv-heading528_084457-aa\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_084457-aa wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading528_084457-aa\">Frequently Asked Questions<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24, .wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24[data-kb-block=\"kb-adv-heading528_b451e7-24\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24[data-kb-block=\"kb-adv-heading528_b451e7-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_b451e7-24[data-kb-block=\"kb-adv-heading528_b451e7-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading528_b451e7-24 wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading528_b451e7-24\">In the process of purchasing and using tire recycling equipment, you may encounter some doubts. So, you can read this page for quick self-help!<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column528_9029ac-e4 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xl, 4rem);}.kadence-column528_9029ac-e4 > .kt-inside-inner-col,.kadence-column528_9029ac-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_9029ac-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_9029ac-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_9029ac-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_9029ac-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_9029ac-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column528_9029ac-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_9029ac-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_9029ac-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns528_ed34be-12{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns528_ed34be-12 .kt-button{font-weight:normal;font-style:normal;}.kt-btns528_ed34be-12 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns528_ed34be-12 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns528_ed34be-12\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button{background:rgba(255,255,255,0);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button:focus{color:var(--global-palette1, #3182CE);background:var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn528_bb8ed6-7f.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn528_bb8ed6-7f kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/8617303831295\" target=\"_blank\" rel=\"noopener\"><span class=\"kt-btn-inner-text\">For more information<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id528_c1cd2c-28 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_c1cd2c-28 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_c1cd2c-28 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_c1cd2c-28 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_c1cd2c-28 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_c1cd2c-28 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_c1cd2c-28 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_5b8a02-b9 > .kt-inside-inner-col,.kadence-column528_5b8a02-b9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_5b8a02-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_5b8a02-b9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_5b8a02-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_5b8a02-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_5b8a02-b9{position:relative;}@media all and (max-width: 1024px){.kadence-column528_5b8a02-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_5b8a02-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_5b8a02-b9\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_0f5198-01{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_0f5198-01 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_0f5198-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_0f5198-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_0f5198-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_0f5198-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_0f5198-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_0f5198-01 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_7c1019-f4 > .kt-inside-inner-col,.kadence-column528_7c1019-f4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_7c1019-f4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_7c1019-f4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_7c1019-f4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_7c1019-f4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_7c1019-f4{position:relative;}@media all and (max-width: 1024px){.kadence-column528_7c1019-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_7c1019-f4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_7c1019-f4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b, .wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b[data-kb-block=\"kb-adv-heading528_1a23af-3b\"]{text-align:center;line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b[data-kb-block=\"kb-adv-heading528_1a23af-3b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_1a23af-3b[data-kb-block=\"kb-adv-heading528_1a23af-3b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_1a23af-3b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading528_1a23af-3b\">Machine Related<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_9e2b19-d8{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_9e2b19-d8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_9e2b19-d8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_9e2b19-d8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_9e2b19-d8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_9e2b19-d8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_9e2b19-d8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_9e2b19-d8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_015447-f2 > .kt-inside-inner-col,.kadence-column528_015447-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_015447-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_015447-f2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_015447-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_015447-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_015447-f2{position:relative;}@media all and (max-width: 1024px){.kadence-column528_015447-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_015447-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_015447-f2\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id528_1cbca4-b7 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242,242,242,0);line-height:1.2;color:var(--global-palette3, #1A202C);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h1, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h2, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h3, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h4, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h5, .kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(242,242,242,0);}.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette1, #3182CE);background:rgba(238,238,238,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(238,238,238,0);}.kt-accordion-id528_1cbca4-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette1, #3182CE);background:rgba(68,68,68,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_1cbca4-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(68,68,68,0);}@media all and (max-width: 1024px){.kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id528_1cbca4-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id528_1cbca4-b7 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id528_1cbca4-b7 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id528_1cbca4-b7 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_1cbca4-b7 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_1cbca4-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_1cbca4-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id528_1cbca4-b7 kt-accordion-has-7-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane528_74468a-d0\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>What tires are our recycling equipment suitable for?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-5-color has-text-color wp-block-paragraph\">All kinds of tires are available, including car tires, truck tires, OTR tires, and so on.<br>Customized recycling solutions are available for different types of tires.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane528_60f442-a3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>What size of rubber powder can I get from the recycling line?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-5-color has-text-color wp-block-paragraph\">10- 40 mesh rubber powder.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane528_72f627-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Whether the device supports fully automatic<\/strong>?.<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Yes, we offer tire recycling solutions from semi-automatic to fully automated, with customized automated control systems.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane528_44d0ac-3b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Whether the equipment meets environmental standards<\/strong>?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Yes, we have CE and ISO certificates and use energy-saving design to ensure that the machine meets environmental standards.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane528_e1f076-f6\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Is it possible to choose parts flexibly?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Yes, we can provide customized equipment to match your production needs.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id528_f6c252-a3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_f6c252-a3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_f6c252-a3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_f6c252-a3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_f6c252-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_f6c252-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_f6c252-a3 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_d5b0f2-70 > .kt-inside-inner-col,.kadence-column528_d5b0f2-70 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_d5b0f2-70 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_d5b0f2-70 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_d5b0f2-70 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_d5b0f2-70 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_d5b0f2-70{position:relative;}@media all and (max-width: 1024px){.kadence-column528_d5b0f2-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_d5b0f2-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_d5b0f2-70\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_25622e-aa{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_25622e-aa > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_25622e-aa > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_25622e-aa > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_25622e-aa > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_25622e-aa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_25622e-aa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_25622e-aa alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_045b05-b7 > .kt-inside-inner-col,.kadence-column528_045b05-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_045b05-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_045b05-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_045b05-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_045b05-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_045b05-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column528_045b05-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_045b05-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_045b05-b7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7, .wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7[data-kb-block=\"kb-adv-heading528_6f57cf-f7\"]{text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7[data-kb-block=\"kb-adv-heading528_6f57cf-f7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_6f57cf-f7[data-kb-block=\"kb-adv-heading528_6f57cf-f7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_6f57cf-f7 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading528_6f57cf-f7\">Operation Related<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_5f5042-b4{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_5f5042-b4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_5f5042-b4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_5f5042-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_5f5042-b4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_5f5042-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_5f5042-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_5f5042-b4 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_a5d445-61 > .kt-inside-inner-col,.kadence-column528_a5d445-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_a5d445-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_a5d445-61 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_a5d445-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_a5d445-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_a5d445-61{position:relative;}@media all and (max-width: 1024px){.kadence-column528_a5d445-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_a5d445-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_a5d445-61\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id528_61bdf4-fb .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242,242,242,0);line-height:1.2;color:var(--global-palette3, #1A202C);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h1, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h2, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h3, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h4, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h5, .kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(242,242,242,0);}.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb .kt-blocks-accordion-header:focus-visible{color:var(--global-palette1, #3182CE);background:rgba(238,238,238,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(238,238,238,0);}.kt-accordion-id528_61bdf4-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette1, #3182CE);background:rgba(68,68,68,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_61bdf4-fb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(68,68,68,0);}@media all and (max-width: 1024px){.kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id528_61bdf4-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id528_61bdf4-fb .kt-accordion-inner-wrap{display:block;}.kt-accordion-id528_61bdf4-fb .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id528_61bdf4-fb .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_61bdf4-fb .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_61bdf4-fb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_61bdf4-fb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id528_61bdf4-fb kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane528_63816d-a4\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>How many people does it take to operate tire recycling equipment?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-5-color has-text-color wp-block-paragraph\">Typically requires 2~4 operators, depending on the level of automation and capacity allocation.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane528_c432d1-89\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>How to adjust the powder size output?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">The powder size can be adjusted by changing the mesh size of the grinding screen or by modifying the gap between grinding rollers (depending on the model).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane528_bd492d-5b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Can the machine run continuously for long hours?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Yes, our machines are designed for long working hours, but we recommend checking wear parts and allowing short pauses for cooling after 8-10 hours of continuous operation.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id528_78b9c5-bf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_78b9c5-bf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_78b9c5-bf > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_78b9c5-bf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_78b9c5-bf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_78b9c5-bf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_78b9c5-bf alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_c7c2a5-da > .kt-inside-inner-col,.kadence-column528_c7c2a5-da > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_c7c2a5-da > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_c7c2a5-da > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_c7c2a5-da > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_c7c2a5-da > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_c7c2a5-da{position:relative;}@media all and (max-width: 1024px){.kadence-column528_c7c2a5-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_c7c2a5-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_c7c2a5-da\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_7eeb4c-b6{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_7eeb4c-b6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_7eeb4c-b6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_7eeb4c-b6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_7eeb4c-b6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_7eeb4c-b6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_7eeb4c-b6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_7eeb4c-b6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_0b5723-45 > .kt-inside-inner-col,.kadence-column528_0b5723-45 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_0b5723-45 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_0b5723-45 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_0b5723-45 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_0b5723-45 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_0b5723-45{position:relative;}@media all and (max-width: 1024px){.kadence-column528_0b5723-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_0b5723-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_0b5723-45\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86, .wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86[data-kb-block=\"kb-adv-heading528_f63eba-86\"]{text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86[data-kb-block=\"kb-adv-heading528_f63eba-86\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_f63eba-86[data-kb-block=\"kb-adv-heading528_f63eba-86\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_f63eba-86 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading528_f63eba-86\">After Service Related<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_65fc1d-4d{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_65fc1d-4d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_65fc1d-4d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_65fc1d-4d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_65fc1d-4d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_65fc1d-4d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_65fc1d-4d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_65fc1d-4d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_10254b-77 > .kt-inside-inner-col,.kadence-column528_10254b-77 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_10254b-77 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_10254b-77 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_10254b-77 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_10254b-77 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_10254b-77{position:relative;}@media all and (max-width: 1024px){.kadence-column528_10254b-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_10254b-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_10254b-77\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id528_af5a43-d1 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242,242,242,0);line-height:1.2;color:var(--global-palette3, #1A202C);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h1, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h2, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h3, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h4, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h5, .kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(242,242,242,0);}.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette1, #3182CE);background:rgba(238,238,238,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(238,238,238,0);}.kt-accordion-id528_af5a43-d1 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette1, #3182CE);background:rgba(68,68,68,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_af5a43-d1:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(68,68,68,0);}@media all and (max-width: 1024px){.kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id528_af5a43-d1 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id528_af5a43-d1 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id528_af5a43-d1 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id528_af5a43-d1 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_af5a43-d1 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_af5a43-d1 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_af5a43-d1 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id528_af5a43-d1 kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane528_3f92b1-ca\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>What about the machine installation?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-5-color has-text-color wp-block-paragraph\">We will send engineers to customer working site for the installation guidance, commissioning and training when everything is ready on the working site, like power, cable, labors, forklift, etc.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane528_225afd-57\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>How about the spare parts?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">We will send one set spare parts for free with machine. And if more, spare parts will be sold at cost price permanently and will give you the spare parts list when you purchase machine.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane528_831ac2-fa\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Will you test the machine before delivery?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Yes, we will test every machine and production line before delivery and send you the working video. You also can come to us for inspection before delivery.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id528_1946eb-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_1946eb-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_1946eb-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_1946eb-a8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_1946eb-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_1946eb-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_1946eb-a8 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_5bdeaa-12 > .kt-inside-inner-col,.kadence-column528_5bdeaa-12 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_5bdeaa-12 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_5bdeaa-12 > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_5bdeaa-12 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_5bdeaa-12 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_5bdeaa-12{position:relative;}@media all and (max-width: 1024px){.kadence-column528_5bdeaa-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_5bdeaa-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_5bdeaa-12\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_b8d675-60{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_b8d675-60 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_b8d675-60 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_b8d675-60 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_b8d675-60 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_b8d675-60 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_b8d675-60 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_b8d675-60 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_1f0724-be > .kt-inside-inner-col,.kadence-column528_1f0724-be > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_1f0724-be > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_1f0724-be > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_1f0724-be > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_1f0724-be > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_1f0724-be{position:relative;}@media all and (max-width: 1024px){.kadence-column528_1f0724-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_1f0724-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_1f0724-be\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8, .wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8[data-kb-block=\"kb-adv-heading528_c70176-e8\"]{text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8[data-kb-block=\"kb-adv-heading528_c70176-e8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_c70176-e8[data-kb-block=\"kb-adv-heading528_c70176-e8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_c70176-e8 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading528_c70176-e8\">Purchase&amp;Shipping<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id528_136bdb-d8{margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id528_136bdb-d8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_136bdb-d8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_136bdb-d8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1000px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id528_136bdb-d8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id528_136bdb-d8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id528_136bdb-d8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_136bdb-d8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column528_926eec-8e > .kt-inside-inner-col,.kadence-column528_926eec-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_926eec-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_926eec-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_926eec-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_926eec-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_926eec-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column528_926eec-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_926eec-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_926eec-8e\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id528_36a197-45 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id528_36a197-45 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242,242,242,0);line-height:1.2;color:var(--global-palette3, #1A202C);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_36a197-45 .kt-accordion-panel-inner, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h1, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h2, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h3, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h4, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h5, .kt-accordion-id528_36a197-45 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(242,242,242,0);}.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_36a197-45 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette1, #3182CE);background:rgba(238,238,238,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(238,238,238,0);}.kt-accordion-id528_36a197-45 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette1, #3182CE);background:rgba(68,68,68,0);border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id528_36a197-45:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(68,68,68,0);}@media all and (max-width: 1024px){.kt-accordion-id528_36a197-45 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_36a197-45 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id528_36a197-45 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id528_36a197-45 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id528_36a197-45 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id528_36a197-45 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id528_36a197-45 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}.kt-accordion-id528_36a197-45 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id528_36a197-45 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette7, #EDF2F7);border-top-style:solid;border-right-color:var(--global-palette7, #EDF2F7);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette7, #EDF2F7);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id528_36a197-45 kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane528_188f71-ee\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>How about the delivery time and packing details?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-5-color has-text-color wp-block-paragraph\">20days after receiving the deposit. Package in the whole container.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane528_f343e3-18\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>How to choose a suitable tire recycling line?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"has-theme-palette-4-color has-text-color wp-block-paragraph\">Please tell us the end product you want to produce, rubber block or rubber powder, and the capacity &amp; output size, we will recommend to you the most suitable tire recycling line.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id528_c26904-67 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id528_c26904-67 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id528_c26904-67 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id528_c26904-67{border-top-left-radius:14px;border-top-right-radius:14px;border-bottom-right-radius:14px;border-bottom-left-radius:14px;isolation:isolate;}.kb-row-layout-id528_c26904-67 > .kt-row-layout-overlay{border-top-left-radius:14px;border-top-right-radius:14px;border-bottom-right-radius:14px;border-bottom-left-radius:14px;}.kb-row-layout-id528_c26904-67{background-image:url('https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/tire-recycling-machines-in-the-factory.webp');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id528_c26904-67 > .kt-row-layout-overlay{opacity:0.80;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id528_c26904-67 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id528_c26904-67 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id528_c26904-67 alignfull has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column528_303f80-2c > .kt-inside-inner-col{display:flex;}.kadence-column528_303f80-2c > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column528_303f80-2c > .kt-inside-inner-col,.kadence-column528_303f80-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_303f80-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column528_303f80-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column528_303f80-2c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column528_303f80-2c > .kt-inside-inner-col{background-color:rgba(255, 255, 255, 0.5);}.kadence-column528_303f80-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_303f80-2c{position:relative;}.kadence-column528_303f80-2c, .kt-inside-inner-col > .kadence-column528_303f80-2c:not(.specificity){margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column528_303f80-2c{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column528_303f80-2c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column528_303f80-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_303f80-2c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35, .wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35[data-kb-block=\"kb-adv-heading528_3afb2b-35\"]{text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35[data-kb-block=\"kb-adv-heading528_3afb2b-35\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_3afb2b-35[data-kb-block=\"kb-adv-heading528_3afb2b-35\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading528_3afb2b-35 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading528_3afb2b-35\">Get More Information<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8, .wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8[data-kb-block=\"kb-adv-heading528_c92d2b-d8\"]{text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8[data-kb-block=\"kb-adv-heading528_c92d2b-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading528_c92d2b-d8[data-kb-block=\"kb-adv-heading528_c92d2b-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading528_c92d2b-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading528_c92d2b-d8\">Our customer service staff is always ready to respond to your questions, please feel free to ask!<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns528_0f085c-43{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns528_0f085c-43 .kt-button{font-weight:normal;font-style:normal;}.kt-btns528_0f085c-43 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns528_0f085c-43 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns528_0f085c-43\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn528_e9cd40-49.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn528_e9cd40-49.kb-button{color:var(--global-palette1, #3182CE);background:var(--global-palette7, #EDF2F7);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn528_e9cd40-49.kb-button{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn528_e9cd40-49.kb-button{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}}<\/style><a class=\"kb-button kt-button button kb-btn528_e9cd40-49 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/8617303831295\" target=\"_blank\" rel=\"noopener\"><span class=\"kt-btn-inner-text\">Contact Us<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column528_b84d75-6d > .kt-inside-inner-col,.kadence-column528_b84d75-6d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column528_b84d75-6d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column528_b84d75-6d > .kt-inside-inner-col{flex-direction:column;}.kadence-column528_b84d75-6d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column528_b84d75-6d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column528_b84d75-6d{position:relative;}@media all and (max-width: 1024px){.kadence-column528_b84d75-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column528_b84d75-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column528_b84d75-6d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image528_85ca41-cf:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:-96px;margin-right:-24px;margin-bottom:-24px;}.kb-image528_85ca41-cf.kb-image-is-ratio-size, .kb-image528_85ca41-cf .kb-image-is-ratio-size{max-width:467px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image528_85ca41-cf.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image528_85ca41-cf .kb-image-is-ratio-size{align-self:unset;}.kb-image528_85ca41-cf{max-width:467px;}.image-is-svg.kb-image528_85ca41-cf{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image528_85ca41-cf img{width:100%;}.kb-image528_85ca41-cf .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image528_85ca41-cf img.kb-img, .kb-image528_85ca41-cf .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image528_85ca41-cf:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-right:0px;margin-bottom:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image528_85ca41-cf size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/Welcome-to-Shuliy-Machinery.webp\" alt=\"Welcome to Shuliy Machinery\" class=\"kb-img wp-image-988\" srcset=\"https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/Welcome-to-Shuliy-Machinery.webp 720w, https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/Welcome-to-Shuliy-Machinery-360x270.webp 360w, https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/Welcome-to-Shuliy-Machinery-180x135.webp 180w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Perguntas Frequentes No processo de compra e utiliza\u00e7\u00e3o de equipamentos de reciclagem de pneus, voc\u00ea pode encontrar algumas d\u00favidas. Portanto, voc\u00ea pode ler esta p\u00e1gina para uma autoajuda r\u00e1pida! Relacionado \u00e0 M\u00e1quina Relacionado \u00e0 Opera\u00e7\u00e3o Relacionado ao Servi\u00e7o P\u00f3s-Venda Compra &amp; Envio Obtenha Mais Informa\u00e7\u00f5es Nossa equipe de atendimento ao cliente est\u00e1 sempre pronta para responder \u00e0s suas perguntas, sinta-se \u00e0 vontade para perguntar!<\/p>","protected":false},"author":1,"featured_media":811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[34],"tags":[61,59],"class_list":["post-528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-support","tag-installation-guide","tag-maintenance"],"taxonomy_info":{"category":[{"value":34,"label":"Support"}],"post_tag":[{"value":61,"label":"installation-guide"},{"value":59,"label":"maintenance"}]},"featured_image_src_large":["https:\/\/www.tirerecyclingline.com\/wp-content\/uploads\/2025\/04\/screenshot_2025-04-16_16-42-59.png",720,540,false],"author_info":{"display_name":"Molly","author_link":"https:\/\/www.tirerecyclingline.com\/pt\/author\/shuliy\/"},"comment_info":0,"category_info":[{"term_id":34,"name":"Support","slug":"support","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":4,"filter":"raw","cat_ID":34,"category_count":4,"category_description":"","cat_name":"Support","category_nicename":"support","category_parent":0}],"tag_info":[{"term_id":61,"name":"installation-guide","slug":"installation-guide","term_group":0,"term_taxonomy_id":61,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"},{"term_id":59,"name":"maintenance","slug":"maintenance","term_group":0,"term_taxonomy_id":59,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/posts\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":1,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"predecessor-version":[{"id":1745,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/posts\/528\/revisions\/1745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/media\/811"}],"wp:attachment":[{"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tirerecyclingline.com\/pt\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}